{"id":2573,"date":"2025-04-28T21:43:41","date_gmt":"2025-04-28T21:43:41","guid":{"rendered":"https:\/\/abogadajulia.com\/?p=2573"},"modified":"2025-04-28T21:43:42","modified_gmt":"2025-04-28T21:43:42","slug":"episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias","status":"publish","type":"post","link":"https:\/\/abogadajulia.com\/pt\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/","title":{"rendered":"Epis\u00f3dio 9 \u2013 Como Falar com as Crian\u00e7as sobre Imigra\u00e7\u00e3o: Gest\u00e3o Emocional e Resili\u00eancia nas Fam\u00edlias"},"content":{"rendered":"<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"EP.9 C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/JNovWHFX77k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"color:#ddd\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-divider-size-1\"><hr style=\"height:30px\"\/><\/div>\n\n\n\n<p>Como falar com seus filhos sobre imigra\u00e7\u00e3o sem causar medo? Neste epis\u00f3dio do Podcast de Imigra\u00e7\u00e3o, a Advogada Julia conversa com a Dra. M\u00f3nica Oganes, psic\u00f3loga escolar e neuropsic\u00f3loga especializada em sa\u00fade emocional infantil, sobre como abordar temas dif\u00edceis como a falta de documentos, o medo da deporta\u00e7\u00e3o e a separa\u00e7\u00e3o familiar.<\/p>","protected":false},"excerpt":{"rendered":"<p>Como falar com seus filhos sobre imigra\u00e7\u00e3o sem causar medo? Neste epis\u00f3dio do Podcast de Imigra\u00e7\u00e3o, a Advogada Julia conversa com a Dra. M\u00f3nica Oganes, psic\u00f3loga escolar e neuropsic\u00f3loga especializada em sa\u00fade emocional infantil, sobre como abordar temas dif\u00edceis como a falta de documentos, o medo da deporta\u00e7\u00e3o e a separa\u00e7\u00e3o familiar.<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-2573","post","type-post","status-publish","format-standard","hentry","category-podcast-de-inmigracion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Episodio 9 - C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abogadajulia.com\/pt\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Episodio 9 - C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo hablar con tus hijos sobre inmigraci\u00f3n sin causarles miedo? En este episodio de El Podcast de Inmigraci\u00f3n, la Abogada Julia conversa con la Dra. M\u00f3nica Oganes, psic\u00f3loga escolar y neuropsic\u00f3loga experta en salud emocional infantil, sobre c\u00f3mo abordar temas dif\u00edciles como la falta de papeles, el miedo a la deportaci\u00f3n y la separaci\u00f3n familiar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abogadajulia.com\/pt\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/\" \/>\n<meta property=\"og:site_name\" content=\"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abogadadeinmigracionjulia\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T21:43:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T21:43:42+00:00\" \/>\n<meta name=\"author\" content=\"Jesus Sarabia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jesus Sarabia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/\"},\"author\":{\"name\":\"Jesus Sarabia\",\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/person\/cf0f2ed6537ce4039eaad0566fa3f731\"},\"headline\":\"Episodio 9 &#8211; C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias\",\"datePublished\":\"2025-04-28T21:43:41+00:00\",\"dateModified\":\"2025-04-28T21:43:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/\"},\"wordCount\":95,\"publisher\":{\"@id\":\"https:\/\/abogadajulia.com\/#organization\"},\"articleSection\":[\"Podcast de Inmigraci\u00f3n\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/\",\"url\":\"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/\",\"name\":\"Episodio 9 - C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\",\"isPartOf\":{\"@id\":\"https:\/\/abogadajulia.com\/#website\"},\"datePublished\":\"2025-04-28T21:43:41+00:00\",\"dateModified\":\"2025-04-28T21:43:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/abogadajulia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Episodio 9 &#8211; C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abogadajulia.com\/#website\",\"url\":\"https:\/\/abogadajulia.com\/\",\"name\":\"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\",\"description\":\"Abogada de Inmigraci\u00f3n - Experta en Visa T\",\"publisher\":{\"@id\":\"https:\/\/abogadajulia.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abogadajulia.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/abogadajulia.com\/#organization\",\"name\":\"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\",\"url\":\"https:\/\/abogadajulia.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/abogadajulia.com\/wp-content\/uploads\/2025\/09\/AJ-GFI_Color_Logo-scaled.png\",\"contentUrl\":\"https:\/\/abogadajulia.com\/wp-content\/uploads\/2025\/09\/AJ-GFI_Color_Logo-scaled.png\",\"width\":2560,\"height\":510,\"caption\":\"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\"},\"image\":{\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/abogadadeinmigracionjulia\/\",\"https:\/\/www.instagram.com\/abogadadeinmigracionjulia\/\",\"https:\/\/www.tiktok.com\/@abogadajulia\",\"https:\/\/www.youtube.com\/channel\/UCgnxaArpnMIRx_2yhI2EYFA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/person\/cf0f2ed6537ce4039eaad0566fa3f731\",\"name\":\"Jesus Sarabia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/abogadajulia.com\/wp-content\/litespeed\/avatar\/a76d3959d51c4d455d0d37cd97e9337d.jpg?ver=1778356109\",\"contentUrl\":\"https:\/\/abogadajulia.com\/wp-content\/litespeed\/avatar\/a76d3959d51c4d455d0d37cd97e9337d.jpg?ver=1778356109\",\"caption\":\"Jesus Sarabia\"},\"url\":\"https:\/\/abogadajulia.com\/pt\/author\/jesushumberto\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Episodio 9 - C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abogadajulia.com\/pt\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/","og_locale":"pt_PT","og_type":"article","og_title":"Episodio 9 - C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","og_description":"\u00bfC\u00f3mo hablar con tus hijos sobre inmigraci\u00f3n sin causarles miedo? En este episodio de El Podcast de Inmigraci\u00f3n, la Abogada Julia conversa con la Dra. M\u00f3nica Oganes, psic\u00f3loga escolar y neuropsic\u00f3loga experta en salud emocional infantil, sobre c\u00f3mo abordar temas dif\u00edciles como la falta de papeles, el miedo a la deportaci\u00f3n y la separaci\u00f3n familiar.","og_url":"https:\/\/abogadajulia.com\/pt\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/","og_site_name":"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","article_publisher":"https:\/\/www.facebook.com\/abogadadeinmigracionjulia\/","article_published_time":"2025-04-28T21:43:41+00:00","article_modified_time":"2025-04-28T21:43:42+00:00","author":"Jesus Sarabia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jesus Sarabia","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/#article","isPartOf":{"@id":"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/"},"author":{"name":"Jesus Sarabia","@id":"https:\/\/abogadajulia.com\/#\/schema\/person\/cf0f2ed6537ce4039eaad0566fa3f731"},"headline":"Episodio 9 &#8211; C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias","datePublished":"2025-04-28T21:43:41+00:00","dateModified":"2025-04-28T21:43:42+00:00","mainEntityOfPage":{"@id":"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/"},"wordCount":95,"publisher":{"@id":"https:\/\/abogadajulia.com\/#organization"},"articleSection":["Podcast de Inmigraci\u00f3n"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/","url":"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/","name":"Episodio 9 - C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","isPartOf":{"@id":"https:\/\/abogadajulia.com\/#website"},"datePublished":"2025-04-28T21:43:41+00:00","dateModified":"2025-04-28T21:43:42+00:00","breadcrumb":{"@id":"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abogadajulia.com\/episodio-9-como-hablar-con-los-ninos-sobre-inmigracion-manejo-emocional-y-resiliencia-en-familias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/abogadajulia.com\/"},{"@type":"ListItem","position":2,"name":"Episodio 9 &#8211; C\u00f3mo hablar con los ni\u00f1os sobre inmigraci\u00f3n: manejo emocional y resiliencia en familias"}]},{"@type":"WebSite","@id":"https:\/\/abogadajulia.com\/#website","url":"https:\/\/abogadajulia.com\/","name":"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","description":"Abogada de Inmigraci\u00f3n - Experta en Visa T","publisher":{"@id":"https:\/\/abogadajulia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abogadajulia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/abogadajulia.com\/#organization","name":"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","url":"https:\/\/abogadajulia.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/abogadajulia.com\/#\/schema\/logo\/image\/","url":"https:\/\/abogadajulia.com\/wp-content\/uploads\/2025\/09\/AJ-GFI_Color_Logo-scaled.png","contentUrl":"https:\/\/abogadajulia.com\/wp-content\/uploads\/2025\/09\/AJ-GFI_Color_Logo-scaled.png","width":2560,"height":510,"caption":"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia"},"image":{"@id":"https:\/\/abogadajulia.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/abogadadeinmigracionjulia\/","https:\/\/www.instagram.com\/abogadadeinmigracionjulia\/","https:\/\/www.tiktok.com\/@abogadajulia","https:\/\/www.youtube.com\/channel\/UCgnxaArpnMIRx_2yhI2EYFA"]},{"@type":"Person","@id":"https:\/\/abogadajulia.com\/#\/schema\/person\/cf0f2ed6537ce4039eaad0566fa3f731","name":"Jesus Sarabia","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/abogadajulia.com\/#\/schema\/person\/image\/","url":"https:\/\/abogadajulia.com\/wp-content\/litespeed\/avatar\/a76d3959d51c4d455d0d37cd97e9337d.jpg?ver=1778356109","contentUrl":"https:\/\/abogadajulia.com\/wp-content\/litespeed\/avatar\/a76d3959d51c4d455d0d37cd97e9337d.jpg?ver=1778356109","caption":"Jesus Sarabia"},"url":"https:\/\/abogadajulia.com\/pt\/author\/jesushumberto\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Jesus Sarabia","author_link":"https:\/\/abogadajulia.com\/pt\/author\/jesushumberto\/"},"_links":{"self":[{"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/posts\/2573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/comments?post=2573"}],"version-history":[{"count":1,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/posts\/2573\/revisions"}],"predecessor-version":[{"id":2574,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/posts\/2573\/revisions\/2574"}],"wp:attachment":[{"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/media?parent=2573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/categories?post=2573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/tags?post=2573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}