{"id":2057,"date":"2024-12-06T16:44:00","date_gmt":"2024-12-06T16:44:00","guid":{"rendered":"https:\/\/abogadajulia.com\/?p=2057"},"modified":"2024-12-09T17:09:54","modified_gmt":"2024-12-09T17:09:54","slug":"episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias","status":"publish","type":"post","link":"https:\/\/abogadajulia.com\/pt\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/","title":{"rendered":"Epis\u00f3dio 01 \u2013 O Impacto das Pol\u00edticas de Imigra\u00e7\u00e3o nas Fam\u00edlias."},"content":{"rendered":"<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Episodio 01 - El impacto de las Poli\u0301ticas de Inmigracio\u0301n en las Familias.\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/GZvnfA1rQxM?list=PLxnxe36TObeYr4dS1tPwxxVNZK2v7CTNF\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Neste epis\u00f3dio, falamos sobre um tema crucial: o impacto das pol\u00edticas de imigra\u00e7\u00e3o nas fam\u00edlias. Desde a separa\u00e7\u00e3o familiar at\u00e9 o medo constante da deporta\u00e7\u00e3o, exploramos como essas pol\u00edticas afetam a vida di\u00e1ria da nossa comunidade imigrante.<\/p>","protected":false},"excerpt":{"rendered":"<p>Neste epis\u00f3dio, falamos sobre um tema crucial: o impacto das pol\u00edticas de imigra\u00e7\u00e3o nas fam\u00edlias. Desde a separa\u00e7\u00e3o familiar at\u00e9 o medo constante da deporta\u00e7\u00e3o, exploramos como essas pol\u00edticas afetam a vida di\u00e1ria da nossa comunidade imigrante.<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[37],"class_list":["post-2057","post","type-post","status-publish","format-standard","hentry","category-podcast-de-inmigracion","tag-chapter-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Episodio 01 - El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias. - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abogadajulia.com\/pt\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Episodio 01 - El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias. - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\" \/>\n<meta property=\"og:description\" content=\"En este episodio, hablamos de un tema crucial: el impacto de las pol\u00edticas de inmigraci\u00f3n en las familias. Desde la separaci\u00f3n familiar hasta el miedo constante a la deportaci\u00f3n , exploramos c\u00f3mo estas pol\u00edticas afectan a nuestra comunidad inmigrante en su vida diaria .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abogadajulia.com\/pt\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/\" \/>\n<meta property=\"og:site_name\" content=\"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abogadadeinmigracionjulia\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-06T16:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-09T17:09:54+00:00\" \/>\n<meta name=\"author\" content=\"Jesus Sarabia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jesus Sarabia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/\"},\"author\":{\"name\":\"Jesus Sarabia\",\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/person\/cf0f2ed6537ce4039eaad0566fa3f731\"},\"headline\":\"Episodio 01 &#8211; El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias.\",\"datePublished\":\"2024-12-06T16:44:00+00:00\",\"dateModified\":\"2024-12-09T17:09:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/\"},\"wordCount\":80,\"publisher\":{\"@id\":\"https:\/\/abogadajulia.com\/#organization\"},\"keywords\":[\"Chapter-1\"],\"articleSection\":[\"Podcast de Inmigraci\u00f3n\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/\",\"url\":\"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/\",\"name\":\"Episodio 01 - El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias. - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\",\"isPartOf\":{\"@id\":\"https:\/\/abogadajulia.com\/#website\"},\"datePublished\":\"2024-12-06T16:44:00+00:00\",\"dateModified\":\"2024-12-09T17:09:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/abogadajulia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Episodio 01 &#8211; El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abogadajulia.com\/#website\",\"url\":\"https:\/\/abogadajulia.com\/\",\"name\":\"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\",\"description\":\"Abogada de Inmigraci\u00f3n - Experta en Visa T\",\"publisher\":{\"@id\":\"https:\/\/abogadajulia.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abogadajulia.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/abogadajulia.com\/#organization\",\"name\":\"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\",\"url\":\"https:\/\/abogadajulia.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/abogadajulia.com\/wp-content\/uploads\/2025\/09\/AJ-GFI_Color_Logo-scaled.png\",\"contentUrl\":\"https:\/\/abogadajulia.com\/wp-content\/uploads\/2025\/09\/AJ-GFI_Color_Logo-scaled.png\",\"width\":2560,\"height\":510,\"caption\":\"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia\"},\"image\":{\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/abogadadeinmigracionjulia\/\",\"https:\/\/www.instagram.com\/abogadadeinmigracionjulia\/\",\"https:\/\/www.tiktok.com\/@abogadajulia\",\"https:\/\/www.youtube.com\/channel\/UCgnxaArpnMIRx_2yhI2EYFA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/person\/cf0f2ed6537ce4039eaad0566fa3f731\",\"name\":\"Jesus Sarabia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/abogadajulia.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/abogadajulia.com\/wp-content\/litespeed\/avatar\/a76d3959d51c4d455d0d37cd97e9337d.jpg?ver=1778356109\",\"contentUrl\":\"https:\/\/abogadajulia.com\/wp-content\/litespeed\/avatar\/a76d3959d51c4d455d0d37cd97e9337d.jpg?ver=1778356109\",\"caption\":\"Jesus Sarabia\"},\"url\":\"https:\/\/abogadajulia.com\/pt\/author\/jesushumberto\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Episodio 01 - El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias. - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abogadajulia.com\/pt\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/","og_locale":"pt_PT","og_type":"article","og_title":"Episodio 01 - El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias. - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","og_description":"En este episodio, hablamos de un tema crucial: el impacto de las pol\u00edticas de inmigraci\u00f3n en las familias. Desde la separaci\u00f3n familiar hasta el miedo constante a la deportaci\u00f3n , exploramos c\u00f3mo estas pol\u00edticas afectan a nuestra comunidad inmigrante en su vida diaria .","og_url":"https:\/\/abogadajulia.com\/pt\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/","og_site_name":"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","article_publisher":"https:\/\/www.facebook.com\/abogadadeinmigracionjulia\/","article_published_time":"2024-12-06T16:44:00+00:00","article_modified_time":"2024-12-09T17:09:54+00:00","author":"Jesus Sarabia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jesus Sarabia","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/#article","isPartOf":{"@id":"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/"},"author":{"name":"Jesus Sarabia","@id":"https:\/\/abogadajulia.com\/#\/schema\/person\/cf0f2ed6537ce4039eaad0566fa3f731"},"headline":"Episodio 01 &#8211; El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias.","datePublished":"2024-12-06T16:44:00+00:00","dateModified":"2024-12-09T17:09:54+00:00","mainEntityOfPage":{"@id":"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/"},"wordCount":80,"publisher":{"@id":"https:\/\/abogadajulia.com\/#organization"},"keywords":["Chapter-1"],"articleSection":["Podcast de Inmigraci\u00f3n"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/","url":"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/","name":"Episodio 01 - El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias. - Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","isPartOf":{"@id":"https:\/\/abogadajulia.com\/#website"},"datePublished":"2024-12-06T16:44:00+00:00","dateModified":"2024-12-09T17:09:54+00:00","breadcrumb":{"@id":"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abogadajulia.com\/episodio-01-el-impacto-de-las-politicas-de-inmigracion-en-las-familias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/abogadajulia.com\/"},{"@type":"ListItem","position":2,"name":"Episodio 01 &#8211; El impacto de las Pol\u00edticas de Inmigraci\u00f3n en las Familias."}]},{"@type":"WebSite","@id":"https:\/\/abogadajulia.com\/#website","url":"https:\/\/abogadajulia.com\/","name":"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","description":"Abogada de Inmigraci\u00f3n - Experta en Visa T","publisher":{"@id":"https:\/\/abogadajulia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abogadajulia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/abogadajulia.com\/#organization","name":"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia","url":"https:\/\/abogadajulia.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/abogadajulia.com\/#\/schema\/logo\/image\/","url":"https:\/\/abogadajulia.com\/wp-content\/uploads\/2025\/09\/AJ-GFI_Color_Logo-scaled.png","contentUrl":"https:\/\/abogadajulia.com\/wp-content\/uploads\/2025\/09\/AJ-GFI_Color_Logo-scaled.png","width":2560,"height":510,"caption":"Abogada de Inmigraci\u00f3n - Experta en Visa T - Abogada Julia"},"image":{"@id":"https:\/\/abogadajulia.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/abogadadeinmigracionjulia\/","https:\/\/www.instagram.com\/abogadadeinmigracionjulia\/","https:\/\/www.tiktok.com\/@abogadajulia","https:\/\/www.youtube.com\/channel\/UCgnxaArpnMIRx_2yhI2EYFA"]},{"@type":"Person","@id":"https:\/\/abogadajulia.com\/#\/schema\/person\/cf0f2ed6537ce4039eaad0566fa3f731","name":"Jesus Sarabia","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/abogadajulia.com\/#\/schema\/person\/image\/","url":"https:\/\/abogadajulia.com\/wp-content\/litespeed\/avatar\/a76d3959d51c4d455d0d37cd97e9337d.jpg?ver=1778356109","contentUrl":"https:\/\/abogadajulia.com\/wp-content\/litespeed\/avatar\/a76d3959d51c4d455d0d37cd97e9337d.jpg?ver=1778356109","caption":"Jesus Sarabia"},"url":"https:\/\/abogadajulia.com\/pt\/author\/jesushumberto\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Jesus Sarabia","author_link":"https:\/\/abogadajulia.com\/pt\/author\/jesushumberto\/"},"_links":{"self":[{"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/posts\/2057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/comments?post=2057"}],"version-history":[{"count":2,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/posts\/2057\/revisions"}],"predecessor-version":[{"id":2059,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/posts\/2057\/revisions\/2059"}],"wp:attachment":[{"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/media?parent=2057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/categories?post=2057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abogadajulia.com\/pt\/wp-json\/wp\/v2\/tags?post=2057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}